{"id":1524,"date":"2019-03-30T03:20:53","date_gmt":"2019-03-30T01:20:53","guid":{"rendered":"http:\/\/overboyaohushua.com\/?page_id=1524"},"modified":"2019-03-30T03:20:53","modified_gmt":"2019-03-30T01:20:53","slug":"model-65-21-6","status":"publish","type":"page","link":"https:\/\/overboyaohushua.com\/index.php\/model-65-21-6\/","title":{"rendered":"GELs &#8211; L\u00edderes (I)"},"content":{"rendered":"\r\n<div class=\"wp-block-image\">\r\n<figure class=\"aligncenter\"><img decoding=\"async\" src=\"http:\/\/wp.cyocaminho.org\/wp-content\/uploads\/2019\/02\/CYCLog-1024x83.png\" alt=\"\" class=\"wp-image-25\" \/>\r\n<figcaption><a href=\"https:\/\/www.cyocaminho.org\">www.cyocaminho.org<\/a><\/figcaption>\r\n<\/figure>\r\n<\/div>\r\n\r\n<p style=\"text-align: center;\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/overboyaohushua.com\/wp-content\/uploads\/2019\/03\/gel1.png\" alt=\"\" width=\"983\" height=\"180\" class=\"alignnone wp-image-1510 size-full\" srcset=\"https:\/\/overboyaohushua.com\/wp-content\/uploads\/2019\/03\/gel1.png 983w, https:\/\/overboyaohushua.com\/wp-content\/uploads\/2019\/03\/gel1-300x55.png 300w, https:\/\/overboyaohushua.com\/wp-content\/uploads\/2019\/03\/gel1-768x141.png 768w, https:\/\/overboyaohushua.com\/wp-content\/uploads\/2019\/03\/gel1-600x110.png 600w\" sizes=\"auto, (max-width: 983px) 100vw, 983px\" \/><\/p>\r\n<p align=\"center\"><em><span style=\"color: #808080; font-size: 28px;\"><b><span style=\"font-family: Verdana;\">Grupos de Estudos Leigos [GELs]<\/span><\/b><\/span><\/em><\/p>\r\n<p align=\"center\"><span style=\"font-size: 28px;\"><b><span style=\"font-family: Verdana;\">ENCONTRO DE L\u00cdDERES &#8211; I<\/span><\/b><\/span><\/p>\r\n<blockquote>\r\n<p style=\"text-align: left;\"><span style=\"font-size: 16px; font-family: 'comic sans ms', sans-serif; color: #808080;\">E disse-lhes: Ide por todo o mundo, e pregai o evangelho a toda criatura.\u00a0 Quem crer e for batizado ser\u00e1 salvo; mas quem n\u00e3o crer ser\u00e1 condenado. Marcus 16:15-16<\/span><\/p>\r\n<\/blockquote>\r\n<p style=\"font-weight: 400; text-align: center;\"><em><span style=\"font-size: 20px;\"><strong>O Princ\u00edpio dos Grupos de Estudos Leigos na B\u00edblia<\/strong><\/span><\/em><\/p>\r\n<p style=\"font-weight: 400; text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>MATERIAL DE TREINAMENTO &#8211; 1\u00aa REUNI\u00c3O<\/strong><\/span><\/p>\r\n<blockquote>\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px; color: #808080;\"><span>No plano da salva\u00e7\u00e3o \u00e9 not\u00f3ria a maneira como o CRIADOR usa o Grupo de Estudos Leigos \u2013 GEL \u2013 para atingir uma grande multid\u00e3o. Do Eden aos nossos dias, Ele sempre lan\u00e7ou m\u00e3o desse princ\u00edpio nos momentos marcantes e decisivos de Sua\u00a0<\/span><span><\/span><span>Igreja\/Kehil\u00e1h<\/span><span>. Estudaremos a seguir algumas dessas interven\u00e7\u00f5es.<\/span><\/span><\/p>\r\n<\/blockquote>\r\n<p id=\"mcetoc_1d762nuil0\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">I \u2013 O PRIMEIRO GRUPO<\/span><\/strong><\/p>\r\n<p id=\"mcetoc_1d762nuil1\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em>Ad\u00e3o e seus Descendentes &#8211;<\/em><\/strong>\u00a0Foi formado por Ad\u00e3o\/Adan e Eva\/Khavyah e a ordem expressa do CRIADOR para o casal foi clara:\u00a0 \u201c<em>E o CRIADOR os aben\u00e7oou e disse: Sede fecunda, multiplique-vos e enchei a terra e sujeitai&#8230;\u201d<\/em>\u00a0Gn 1:28. Aqui o CRIADOR usa um casal para atingir uma grande multid\u00e3o.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><\/p>\r\n<p id=\"mcetoc_1d762nuim2\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">II \u2013 O SEGUNDO GRUPO<\/span><\/strong><\/p>\r\n<p id=\"mcetoc_1d762nuim3\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em>Teve como componentes No\u00e9\/Nokh e sua fam\u00edlia &#8211;\u00a0<\/em><\/strong>Agora o CRIADOR reduz a multid\u00e3o corrupta a um Grupo liderado por No\u00e9. A B\u00edblia descreve algumas caracter\u00edsticas dele: Gn 6:8,9: \u201c<em>Por\u00e9m, Nokh achou gra\u00e7a diante do Criador<\/em>.\u201d Eis a hist\u00f3ria de No\u00e9\/Nokh<em>:\u00a0 \u201cEra homem justo e \u00edntegro entre os seus contempor\u00e2neos, Nokh andava com o CRIADOR<\/em>.\u201d A terra agora vai ser povoada por um Grupo (8 pessoas) novamente e com a b\u00ean\u00e7\u00e3o do CRIADOR. Gn 9:1:\u00a0 \u201c<em>Aben\u00e7oou o CRIADOR a Nokh e a seus filhos disse: Sede fecundos, multiplicai-vos e enchei a terra\u201d e o CRIADOR firmou uma\u00a0Alian\u00e7a com Nokh de que a terra nunca mais seria destru\u00edda por um dil\u00favio<\/em>. Gn 9:9,10.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Portanto, uma grande multid\u00e3o foi reduzida a um Grupo e agora este formar\u00e1 uma multid\u00e3o novamente.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>III \u2013 O TERCEIRO GRUPO \u00a0<\/strong><\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>Foi formado por\u00a0Abra\u00e3o\/Abrul&#8217;han\u00a0e seus descendentes<\/strong>\u00a0&#8211; Este\u00a0Abra\u00e3o\/Abrul&#8217;han, o CRIADOR tira do meio da multid\u00e3o, para que atrav\u00e9s dele, fosse formada uma nova multid\u00e3o com uma nova maneira de pensar e agir em rela\u00e7\u00e3o ao CRIADOR e ao pr\u00f3ximo. O processo grupo-multid\u00e3o \u00e9 novamente repetido. O l\u00edder escolhido por o CRIADOR era um homem rico e que morava numa terra pag\u00e3, distante. Escutemos o chamado do CRIADOR para ele:\u00a0 \u201c<em>Ora, disse o Criador a\u00a0<\/em><em>Abra\u00e3o\/Abrul&#8217;han: Sai da tua terra, da tua parentela e da casa de teu pai e vai para uma terra que te mostrarei; de te farei uma grande na\u00e7\u00e3o e te aben\u00e7oarei e te engrandecerei o nome. S\u00ea tu uma b\u00ean\u00e7\u00e3o<\/em>.\u201d Gn 12:12.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>O prop\u00f3sito do CRIADOR cumprido<\/strong>\u00a0&#8211;\u00a0Abra\u00e3o\/Abrul&#8217;han\u00a0j\u00e1 havia morrido, a grande multid\u00e3o estava formada, mas havia um problema, ela estava no cativeiro do Egito, paganizada novamente. o CRIADOR novamente interveio, chamou um novo l\u00edder para libertar o povo e conduzi-lo a Cana\u00e3. Ele escolheu Mois\u00e9s e seu irm\u00e3o Ar\u00e3o. Assim o CRIADOR falou a Mois\u00e9s\/Mehushua:\u00a0 \u201c<em>Eu serei contigo, &#8230; Eu Sou o que Sou&#8230; vai, pois, agora e Eu serei com a tua boca e te ensinarei o que h\u00e1s de falar&#8230; e vos ensinarei o que deveis fazer<\/em>.\u201d Gn 3:11, 14; 4:12 e 15.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O CRIADOR libertou o povo de forma sobrenatural, mas havia agora outro problema: a lideran\u00e7a da multid\u00e3o estava centralizada apenas em um homem, este era uma pessoa boa, respons\u00e1vel e temente a o CRIADOR, mas precisava \u201caprender\u201d novos princ\u00edpios de lideran\u00e7a.<\/span><\/p>\r\n<p id=\"mcetoc_1d762nuim4\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em>O CRIADOR fala ao L\u00edder &#8211;<\/em><\/strong>\u00a0\u00a0 O contexto era esse; O sogro de Mois\u00e9s\/Mehushua escuta as not\u00edcias acerca do que o CRIADOR estava fazendo atrav\u00e9s dele (Mois\u00e9s\/Mehushua) e vai ao acampamento e aproveita para levar a fam\u00edlia de Mois\u00e9s\/Mehushua. Jetro\/Yaothron estava encantado com tudo o que estava presenciando, mas viu um quadro que lhe deixou estarrecido, chocado, perplexo, preocupado: um homem s\u00f3 querendo fazer tudo, centralizando as coisas e querendo atender a todos. Imagine o quadro: Filas quilom\u00e9tricas, o povo aborrecido, reclamando, e Mois\u00e9s\/Mehushua cansado, sem tempo para a fam\u00edlia e quanto mais trabalhava mais o trabalho se multiplicava. Um observador \u00e0 dist\u00e2ncia vendo tudo aquilo e pensando:\u00a0<em>Pobre deste povo. Coitado deste l\u00edder. Para onde ir\u00e3o?<\/em><\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em>\u00a0\u00a0\u00a0\u00a0\u00a0 Vamos ler \u00caxodo 18:13-23 e responder \u00e0 medida que fazem a leitura, as seguintes perguntas:<\/em><\/strong><\/span><\/p>\r\n<ul>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O que o sogro de Mois\u00e9s\/Mehushua o viu fazer? Verso 13<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Quais as duas perguntas que Jetro\/Yaothron fez? Verso 14<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Qual a resposta de Mois\u00e9s\/Mehushua ? Verso 15 e 16<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Qual a repreens\u00e3o de Jetro\/Yaothron? Versos 17 e 18<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Conselho: Versos 19-23<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Mois\u00e9s\/Mehushua aceitou e colocou em pr\u00e1tica a orienta\u00e7\u00e3o? Versos 24 e 25<\/span><\/p>\r\n<\/li>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Qual foi o comportamento do povo e de Mois\u00e9s\/Mehushua? Verso 26<\/span><\/p>\r\n<\/li>\r\n<\/ul>\r\n<p id=\"mcetoc_1d762nuim5\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Nota: O l\u00edder inteligente muda antes do caos chegar completamente.<\/span><\/p>\r\n<p id=\"mcetoc_1d762nuim6\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">\u00a0<\/span><\/p>\r\n<p id=\"mcetoc_1d762nuim7\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">IV &#8211; O QUARTO GRUPO<\/span><\/strong><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Foi liderado por Yaohushua num tempo da hist\u00f3ria da humanidade \u2013 \u201c<em>Vindo, por\u00e9m, a plenitude do tempo, o ETERNO enviou Seu Filho, nascido de mulher, nascido sob a lei, para resgatar os que estavam sob a lei, a fim de que receb\u00eassemos a ado\u00e7\u00e3o de filhos.<\/em>\u201d Gl 4:4,5.<\/span><\/p>\r\n<p id=\"mcetoc_1d762nuim8\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>Ora\u00e7\u00e3o e Escolha do Grupo<\/strong>\u00a0&#8211; \u201cNaqueles dias, retirou-Se para o monte a fim de orar, e passou a noite com o ETERNO. E quando amanheceu, chamou a si os Seus disc\u00edpulos e escolheu doze entre eles, aos quais deu tamb\u00e9m o nome de ap\u00f3stolos\u201d. Lc 12 e 13.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">\u201c<em>Tendo Yaohushua convocado os doze, deu-lhes poder e autoridade sobre os dem\u00f4nios e efetuar curas. Tamb\u00e9m os enviou a pregar o Reino do ETERNO e a curar os enfermos<\/em>.\u201d Lc 9:1-2.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">INICIALMENTE,\u00a0<strong>a sinagoga<\/strong>\u00a0foi o primeiro campo de evangeliza\u00e7\u00e3o. A organiza\u00e7\u00e3o lit\u00fargica estava voltada para a promo\u00e7\u00e3o \u00e0 disciplina, devo\u00e7\u00e3o e estudo.\u00a0 O culto consistia de Shemah, a ora\u00e7\u00e3o, da leitura da Lei e dos\u00a0Profetas, \u00e0 qual geralmente seguia-se uma explana\u00e7\u00e3o e da b\u00ean\u00e7\u00e3o. Qualquer membro da congrega\u00e7\u00e3o podia ser convocado para ler as\u00a0Escrituras; e, qualquer um podia fazer a explana\u00e7\u00e3o\u201d.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Os crist\u00e3os n\u00e3o perderam estas oportunidades e nas tr\u00eas primeiras d\u00e9cadas, puderam evangelizar muitas pessoas que frequentavam as sinagogas. Geralmente iniciavam a sua explana\u00e7\u00e3o falando da hist\u00f3ria de Israel\/Yaoshor\u2019ul, para mostrar que tinham a mesma origem e f\u00e9, e finalmente chegavam ao cl\u00edmax da auto-revela\u00e7\u00e3o do CRIADOR. Yaohushua, morto e ressurreto, como verdadeiro Messias que veio para salvar Israel\/Yaoshor\u2019ul. Mas as portas das sinagogas se fecharam\u00a0 e n\u00e3o puderam mais pregar livremente nas reuni\u00f5es. Leia Ec 1:9.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Partiram para a prega\u00e7\u00e3o ao ar livre como Yaohushua fazia. \u201cA prega\u00e7\u00e3o era centralizada na pessoa, miss\u00e3o, paix\u00e3o, ressurrei\u00e7\u00e3o e poder de Yaohushua hol\u2019Mehushkyah\u201d. Evangeliza\u00e7\u00e3o na Igreja Primitiva. Mas logo veio a persegui\u00e7\u00e3o, o que facilitou a divis\u00e3o dos crentes em Grupos de Estudos Leigos para estudo, discuss\u00e3o e debate do evangelho nas casas particulares, e tal procedimento passou a ser uma estrat\u00e9gia fundamental na divulga\u00e7\u00e3o do Evangelho. Quando os m\u00e9todos tradicionais falharam, os Grupos de Estudos Leigos tomaram a dianteira e assumiram a unidade e a centralidade no plano mestre de evangeliza\u00e7\u00e3o.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">A evangeliza\u00e7\u00e3o nos lares passou a ser um elemento significativo e b\u00e1sico para a proclama\u00e7\u00e3o do evangelho.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>Os fatores determinantes do sucesso dos Grupos de Estudos Leigos naqueles dias foram:<\/strong><\/span><\/p>\r\n<ol>\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em><\/em><\/strong><strong><em>Poucas pessoas<\/em><\/strong><\/span><\/p>\r\n<\/li>\r\n<\/ol>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O n\u00famero pequeno de pessoas em cada grupo facilitava a troca de id\u00e9ias e os assuntos eram completamente debatidos.<\/span><\/p>\r\n<ol start=\"2\">\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em><\/em><\/strong><strong><em>O L\u00edder junto do povo<\/em><\/strong><\/span><\/p>\r\n<\/li>\r\n<\/ol>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O dirigente n\u00e3o ficava isolado do povo como no templo, sinagoga e a prega\u00e7\u00e3o ao ar livre, ele estava junto \u00e0s pessoas, levantava os assuntos e coordenava os debates, e assim a verdade era ensinada e os la\u00e7os de amizade eram estreitados.<\/span><\/p>\r\n<ol start=\"3\">\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em><\/em><\/strong><strong><em>Ambiente Informal<\/em><\/strong><\/span><\/p>\r\n<\/li>\r\n<\/ol>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O lar era um ambiente informal e descontra\u00eddo, o que propiciava a livre participa\u00e7\u00e3o de todos, num clima de amizade e busca de edifica\u00e7\u00e3o m\u00fatua em Cristo e uns aos outros.<\/span><\/p>\r\n<ol start=\"4\">\r\n<li style=\"font-weight: 400;\">\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em><\/em><\/strong><strong><em>Hospitalidade<\/em><\/strong><\/span><\/p>\r\n<\/li>\r\n<\/ol>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">O anfitri\u00e3o recebia seus convidados como se fossem o pr\u00f3prio Cristo; o crente apreciava receber crentes e muito mais aqueles que vinham em busca de Cristo. A hospitalidade foi um fator importante no programa de evangeliza\u00e7\u00e3o da Igreja Primitiva.<\/span><\/p>\r\n<p id=\"mcetoc_1d762nuim9\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>\u00a0\u00a0\u00a0<\/strong><\/span><\/p>\r\n<p id=\"mcetoc_1d762nuima\" style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 20px;\"><strong>AS IGREJAS NOS LARES<\/strong><\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong><em>\u00a0\u00a0\u00a0 Logo as igrejas nos lares espalharam-se por toda parte:<\/em><\/strong><\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">o\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Em Tessal\u00f4nica funcionava na casa de Yason. Atos 17:5<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">o\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Em Corinto a igreja estava na casa de Teitus, o justo, em frente \u00e0 sinagoga. Atos 18:7<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">o\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0A casa de Fylyp em Cesar\u00e9ia, onde Paulo\/Sha&#8217;ul era hospedado. Atos 21:8<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">o\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0As casas de L\u00eddia e do carcereiro de Filipos\/Fylypsiyah foram usadas. Atos 15:15, 32-34.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">o\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Uma oholyao na casa da m\u00e3e de J. Marcus, em\u00a0Jerusal\u00e9m\/Yah&#8217;shua-oleym. Atos 12:12<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Os Grupos de Estudos Leigos ou as oholyaos nos lares se tornaram a estrat\u00e9gia determinante na difus\u00e3o da f\u00e9 crist\u00e3.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>CONCLUS\u00c3O:<\/strong><\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Resultados extraordin\u00e1rios foram conseguidos em pouco tempo; n\u00e3o \u00e9 de se admirar a declara\u00e7\u00e3o de Paulo\/Sha&#8217;ul:\u00a0 \u201c<em>Se \u00e9 que permaneceis na f\u00e9, alicer\u00e7ados e firmes, n\u00e3o vos deixando afastar da esperan\u00e7a do evangelho que ouviste e que foi pregado a toda criatura debaixo do c\u00e9u, do qual eu, Paulo\/Sha&#8217;ul, me tornei ministro<\/em>.\u201d Cl 1:23.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Qual foi o segredo de t\u00e3o grande \u00eaxito? \u00a0\u201c<em>E todos os dias no templo e\u00a0<strong>de casa em casa<\/strong>, n\u00e3o cessavam de ensinar e pregar Yaohushua hol\u2019Mehushkyah<\/em>.\u201d Atos 5:42.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\"><strong>NOTA:<\/strong>\u00a0Esta \u00e9 a oportunidade de apresentar a mensagem do ETERNO, \u00fanico!<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">At\u00e9 os incr\u00e9dulos reconheceram o sucesso alcan\u00e7ado pelos mission\u00e1rios da Igreja Primitiva. Escutem como foi a rea\u00e7\u00e3o em Tessal\u00f4nica\/Teslonikyah:\u00a0 \u201c<em>&#8230;estes que t\u00eam transtornado o mundo chegaram tamb\u00e9m aqui.<\/em>\u201d Atos 17:6 u.p.<\/span><\/p>\r\n<p style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px;\">Amnao!<\/span><\/p>\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px; color: #808080;\"><strong>OBS<\/strong>: Clic para Ver um Estudo sobre:\u00a0<strong><a href=\"https:\/\/www.cyocaminho.org\/EstruturaCulto.html\" style=\"color: #808080;\">A Estrutura de Um Culto<\/a><\/strong><\/span><\/p>\r\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px; color: #808080;\"><strong>NOTA de oCaminho<\/strong>: Todo GEL pode e deve se tornar uma futura Oholyao, onde a Verdade \u00e9 ensinada!<\/span><\/p>\r\n<p><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 16px; color: #808080;\"><a href=\"http:\/\/overboyaohushua.com\/index.php\/model-65-22\/\" style=\"color: #808080;\">CLIC AQUI para saber como dar estudos b\u00edblicos&#8230;<\/a><\/span><\/strong><\/p>\r\n<p>&nbsp;<\/p>\r\n<p style=\"text-align: center;\"><b><span style=\"color: #808080; font-family: Verdana;\"> <a href=\"http:\/\/overboyaohushua.com\/index.php\/principal-6\/\"><span style=\"color: #808080;\"> <marquee>Seja um Rosh (l\u00edder Congregacional); fa\u00e7a o CTA: Curso de Teologia Aplicada &#8211; CLIC!<\/marquee><\/span><\/a><\/span><\/b><\/p>\r\n\r\n<p class=\"wp-block-paragraph\"><strong>D\u00favidas:<\/strong><\/p>\r\n\r\n\r\n\t\t\t<link rel=\"stylesheet\" property=\"stylesheet\" href=\"https:\/\/overboyaohushua.com\/wp-content\/plugins\/happyforms\/bundles\/css\/frontend.css\" \/>\n\t\t\t\t<!-- HappyForms CSS variables -->\n\t<style>\n\t#happyforms-54 {\n\t\t--happyforms-part-title-font-size: 16px;\n--happyforms-part-description-font-size: 14px;\n--happyforms-part-value-font-size: 16px;\n--happyforms-submit-button-font-size: 18px;\n--happyforms-color-primary: #000000;\n--happyforms-color-success-notice: #ebf9f0;\n--happyforms-color-success-notice-text: #1eb452;\n--happyforms-color-error: #ff7550;\n--happyforms-color-error-notice: #ffeeea;\n--happyforms-color-error-notice-text: #f23000;\n--happyforms-color-part-title: #000000;\n--happyforms-color-part-value: #000000;\n--happyforms-color-part-placeholder: #888888;\n--happyforms-color-part-description: #454545;\n--happyforms-color-part-border: #dbdbdb;\n--happyforms-color-part-border-focus: #407fff;\n--happyforms-color-part-background: #ffffff;\n--happyforms-color-part-background-focus: #ffffff;\n--happyforms-color-submit-background: #407fff;\n--happyforms-color-submit-background-hover: #3567cc;\n--happyforms-color-submit-border: transparent;\n--happyforms-color-submit-text: #ffffff;\n--happyforms-color-submit-text-hover: #ffffff;\n--happyforms-color-table-row-odd: #fcfcfc;\n--happyforms-color-table-row-even: #efefef;\n--happyforms-color-table-row-odd-text: #000000;\n--happyforms-color-table-row-even-text: #000000;\n--happyforms-color-dropdown-item-bg: #ffffff;\n--happyforms-color-dropdown-item-text: #000000;\n--happyforms-color-dropdown-item-bg-hover: #dbdbdb;\n--happyforms-color-dropdown-item-text-hover: #000000;\n--happyforms-color-divider-hr: #cccccc;\n--happyforms-color-choice-checkmark-bg: #ffffff;\n--happyforms-color-choice-checkmark-bg-focus: #000000;\n--happyforms-color-choice-checkmark-color: #ffffff;\n\t}\n\t<\/style>\n\t<!-- End of HappyForms CSS variables -->\n\t\t<!-- HappyForms Additional CSS -->\n\t<style data-happyforms-additional-css>\n\t\t<\/style>\n\t<!-- End of HappyForms Additional CSS -->\n\t\t\t<link rel=\"stylesheet\" type=\"text\/css\" href=\"https:\/\/overboyaohushua.com\/wp-content\/plugins\/happyforms\/core\/assets\/css\/no-interaction.css\">\n\t\t<div class=\"happyforms-form happyforms-styles\" id=\"happyforms-54\">\n\t\t\n\t<form action=\"\" id=\"happyforms-form-54\" method=\"post\" novalidate=\"true\" autocomplete=\"off\">\n\t\t\t\t<input type=\"hidden\" name=\"happyforms_random_seed\" value=\"228609668\" \/>\n\t\t\n\t\t\t<input type=\"hidden\" name=\"action\" value=\"happyforms_message\">\n\t\t\t\t<input type=\"hidden\" name=\"client_referer\" value=\"\">\n\t\t\t\t<input type=\"hidden\" name=\"current_post_id\" value=\"\">\n\t\t\t\t<input type=\"hidden\" name=\"happyforms_form_id\" value=\"54\" \/>\n\t\t\t\t<input type=\"hidden\" name=\"happyforms_step\" value=\"0\" \/>\n\t\n\t\t<div class=\"happyforms-flex\">\n\t\t\t\t<input type=\"text\" name=\"54-multi_line_text\" style=\"position:absolute;left:-5000px;\" tabindex=\"-1\" autocomplete=\"off\" aria-hidden=\"true\"> <span class=\"screen-reader-text\">Leave this field blank<\/span>\n\t\t\t\t\t\t\t\t\t\t<div class=\"happyforms-form__part happyforms-part happyforms-part--single_line_text happyforms-part--width-full happyforms-part--label-above\" id=\"happyforms-54_single_line_text_1-part\" data-happyforms-type=\"single_line_text\" data-happyforms-id=\"single_line_text_1\" data-happyforms-required=\"\">\n\t<div class=\"happyforms-part-wrap\">\n\t\t\n\t\t\t\t\t\t<div class=\"happyforms-part__label-container\">\n\t\t\t\t<label for=\"happyforms-54_single_line_text_1\" class=\"happyforms-part__label\">\n\t\t\t<span class=\"label\">Nome<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-required\"><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-optional\">(optional)<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\n\t\t\n\t\t<div class=\"happyforms-part__el\">\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"happyforms-input\">\n\t\t\t\t\n\t\t\t\t<input id=\"happyforms-54_single_line_text_1\" type=\"text\" name=\"54_single_line_text_1\" value=\"\" placeholder=\"\" autocomplete=\"off\" spellcheck=\"false\"  autocorrect=\"off\" \/>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"happyforms-part--with-autocomplete happyforms-form__part happyforms-part happyforms-part--email happyforms-part--width-full happyforms-part--label-above\" id=\"happyforms-54_email_7-part\" data-happyforms-type=\"email\" data-happyforms-id=\"email_7\" data-happyforms-required=\"\">\n\t\t<div class=\"happyforms-part-wrap\">\n\t\t\t\t\t\t<div class=\"happyforms-part__label-container\">\n\t\t\t\t<label for=\"happyforms-54_email_7\" class=\"happyforms-part__label\">\n\t\t\t<span class=\"label\">Email<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-required\"><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-optional\">(optional)<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\n\t\t\n\t\t<div class=\"happyforms-part__el\">\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"happyforms-input\">\n\t\t\t\t<input type=\"email\" name=\"54_email_7\" id=\"happyforms-54_email_7\" value=\"\" placeholder=\"\" autocomplete=\"off\" spellcheck=\"false\"  autocorrect=\"off\" \/>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"happyforms-form__part happyforms-part happyforms-part--single_line_text happyforms-part--width-full happyforms-part--label-above\" id=\"happyforms-54_single_line_text_2-part\" data-happyforms-type=\"single_line_text\" data-happyforms-id=\"single_line_text_2\" data-happyforms-required=\"\">\n\t<div class=\"happyforms-part-wrap\">\n\t\t\n\t\t\t\t\t\t<div class=\"happyforms-part__label-container\">\n\t\t\t\t<label for=\"happyforms-54_single_line_text_2\" class=\"happyforms-part__label\">\n\t\t\t<span class=\"label\">Cidade+ Estado<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-required\"><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-optional\">(optional)<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\n\t\t\n\t\t<div class=\"happyforms-part__el\">\n\t\t\t\n\t\t\t\n\t\t\t<div class=\"happyforms-input\">\n\t\t\t\t\n\t\t\t\t<input id=\"happyforms-54_single_line_text_2\" type=\"text\" name=\"54_single_line_text_2\" value=\"\" placeholder=\"\" autocomplete=\"off\" spellcheck=\"false\"  autocorrect=\"off\" \/>\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<div class=\"happyforms-form__part happyforms-part happyforms-part--multi_line_text happyforms-part--width-full happyforms-part--label-above\" id=\"happyforms-54_multi_line_text_6-part\" data-happyforms-type=\"multi_line_text\" data-happyforms-id=\"multi_line_text_6\" data-happyforms-required=\"\">\n\t<div class=\"happyforms-part-wrap\">\n\t\t\t\t\t\t<div class=\"happyforms-part__label-container\">\n\t\t\t\t<label for=\"happyforms-54_multi_line_text_6\" class=\"happyforms-part__label\">\n\t\t\t<span class=\"label\">Mensagem<\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-required\"><\/span>\n\t\t\t\t\t\t\t\t\t\t<span class=\"happyforms-optional\">(optional)<\/span>\n\t\t\t\t\t<\/label>\n\t\t\t<\/div>\n\t\t\t\n\t\t\n\t\t<div class=\"happyforms-part__el\">\n\t\t\t\n\t\t\t\t\t\t<textarea id=\"happyforms-54_multi_line_text_6\" name=\"54_multi_line_text_6\" rows=\"5\" placeholder=\"\" autocomplete=\"off\" spellcheck=\"false\" autocorrect=\"off\" ><\/textarea>\n\t\t\t\n\t\t\t\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n\t\t\t\t\t\t<div class=\"happyforms-form__part happyforms-part happyforms-part--submit\">\n\t\t<button type=\"submit\" class=\"happyforms-submit happyforms-button--submit \">ENVIAR<\/button>\n\t<\/div>\t\t<\/div>\n\n\t\t\t<\/form>\n\n\t<\/div>\n\n<div style='text-align:left' class='yasr-auto-insert-overall'><\/div><div style='text-align:left' class='yasr-auto-insert-visitor'><\/div>","protected":false},"excerpt":{"rendered":"<p>Grupos de Estudos Leigos [GELs] ENCONTRO DE L\u00cdDERES &#8211; I E disse-lhes: Ide por todo o mundo, e pregai o evangelho a toda criatura.\u00a0 Quem crer e for batizado ser\u00e1 salvo; mas quem n\u00e3o crer ser\u00e1 condenado. Marcus 16:15-16 O Princ\u00edpio dos Grupos de Estudos Leigos na B\u00edblia MATERIAL DE TREINAMENTO &#8211; 1\u00aa REUNI\u00c3O No [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"yasr_overall_rating":0,"yasr_post_is_review":"","yasr_auto_insert_disabled":"","yasr_review_type":"","footnotes":""},"class_list":["post-1524","page","type-page","status-publish","hentry"],"yasr_visitor_votes":{"stars_attributes":{"read_only":false,"span_bottom":false},"number_of_votes":0,"sum_votes":0},"_links":{"self":[{"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/pages\/1524","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/comments?post=1524"}],"version-history":[{"count":1,"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/pages\/1524\/revisions"}],"predecessor-version":[{"id":1531,"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/pages\/1524\/revisions\/1531"}],"wp:attachment":[{"href":"https:\/\/overboyaohushua.com\/index.php\/wp-json\/wp\/v2\/media?parent=1524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}